{"id":71170,"date":"2026-07-14T15:29:45","date_gmt":"2026-07-14T13:29:45","guid":{"rendered":"https:\/\/www.fokussrl.com\/?post_type=product&#038;p=71170"},"modified":"2026-07-14T15:40:54","modified_gmt":"2026-07-14T13:40:54","slug":"chaudiere-gaz-a-condensation-logamax-plus-gb-172i-buderus-copia","status":"publish","type":"product","link":"https:\/\/www.fokussrl.com\/fr\/produit\/chaudiere-gaz-a-condensation-logamax-plus-gb-172i-buderus-copia\/","title":{"rendered":"Chaudi\u00e8re gaz \u00e0 condensation LOGAMAX PLUS GB 172i &#8211; Buderus (Copia)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>La chaudi\u00e8re murale \u00e0 condensation offre une excellente combinaison de beaut\u00e9 et d&rsquo;innovation, avec les caract\u00e9ristiques suivantes:<\/p>\n<ul>\n<li>\n<p><strong>Design raffin\u00e9 et attrayant<\/strong>: La fa\u00e7ade en verre tremp\u00e9 au titane lui conf\u00e8re une apparence \u00e9l\u00e9gante et moderne. Disponible en versions blanche ou noire, elle s&rsquo;int\u00e8gre parfaitement dans tout environnement domestique.<\/p>\n<\/li>\n<li>\n<p><strong>Efficacit\u00e9 \u00e9nerg\u00e9tique \u00e9lev\u00e9e<\/strong>: Gr\u00e2ce \u00e0 la technologie \u00e0 condensation, elle garantit une utilisation optimale de l&rsquo;\u00e9nergie, r\u00e9duisant les gaspillages et offrant des performances exceptionnelles.<\/p>\n<\/li>\n<li>\n<p><strong>R\u00e9glage automatique de la puissance et de la consommation<\/strong>: La chaudi\u00e8re s&rsquo;adapte automatiquement \u00e0 vos besoins de chauffage, optimisant la puissance et r\u00e9duisant la consommation d&rsquo;\u00e9nergie, assurant un confort optimal sans gaspillage.<\/p>\n<\/li>\n<li>\n<p><strong>Gestion \u00e0 distance via App<\/strong>: Vous pouvez contr\u00f4ler et g\u00e9rer la chaudi\u00e8re \u00e0 distance via une application d\u00e9di\u00e9e, permettant un contr\u00f4le complet du chauffage m\u00eame lorsque vous \u00eates absent. Cela est possible en combinaison avec le thermostat intelligent Logamatic TC100.<\/p>\n<\/li>\n<\/ul>\n<p>En r\u00e9sum\u00e9, cette chaudi\u00e8re combine esth\u00e9tique et fonctionnalit\u00e9, offrant non seulement des performances \u00e9nerg\u00e9tiques \u00e9lev\u00e9es mais aussi un contr\u00f4le intuitif et flexible, rendant le confort domestique encore plus agr\u00e9able et pratique.<\/p>\n","protected":false},"featured_media":71223,"template":"","meta":{"_acf_changed":false},"product_brand":[4799],"product_cat":[4573],"product_tag":[4842],"class_list":["post-71170","product","type-product","status-publish","has-post-thumbnail","product_brand-buderus-fr","product_cat-chaudieres-a-gaz","product_tag-caldaie-a-gas","product_shipping_class-caldaie-a-gas-2-2","pa_potenza-24-24-kw-fr","sales-flash-overlay","woocommerce-text-align-center","woocommerce-image-align-center","do-quantity-buttons","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.fokussrl.com\/fr\/wp-json\/wp\/v2\/product\/71170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fokussrl.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.fokussrl.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fokussrl.com\/fr\/wp-json\/wp\/v2\/media\/71223"}],"wp:attachment":[{"href":"https:\/\/www.fokussrl.com\/fr\/wp-json\/wp\/v2\/media?parent=71170"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.fokussrl.com\/fr\/wp-json\/wp\/v2\/product_brand?post=71170"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.fokussrl.com\/fr\/wp-json\/wp\/v2\/product_cat?post=71170"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.fokussrl.com\/fr\/wp-json\/wp\/v2\/product_tag?post=71170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}