{"id":54279,"date":"2025-02-01T16:51:56","date_gmt":"2025-02-01T15:51:56","guid":{"rendered":"http:\/\/fokussrl.com\/prodotto\/caldaia-bicombustibile-compact-power-plus-pasqualicchio\/"},"modified":"2025-02-01T16:51:57","modified_gmt":"2025-02-01T15:51:57","slug":"caldaia-bicombustibile-compact-power-plus-pasqualicchio","status":"publish","type":"product","link":"https:\/\/www.fokussrl.com\/it\/prodotto\/caldaia-bicombustibile-compact-power-plus-pasqualicchio\/","title":{"rendered":"Caldaia bicombustibile COMPACT POWER PLUS &#8211; Pasqualicchio"},"content":{"rendered":"<ul>\n<li>HYBRID BI-POWER policombustibile.<\/li>\n<li>SONDA LAMBDA rilevazione della concentrazione di ossigeno all&#8217;interno del gas di scarico.<\/li>\n<li>BASSE EMISSIONI valori di polveri sottili immesse nell&#8217;aria.<\/li>\n<li>STELLE AMBIENTALI certificazione alte performance ambientali. 25-60-80 kW 5 Stelle Ambientali<\/li>\n<li>30-40-50-100 kW 4 Stelle Ambientali<\/li>\n<li>ATTUATORI sistema elettrico che regola i registri di aria primaria e secondaria e la velocit&agrave; degli aspiratori dei fumi. A+ classe energetica.<\/li>\n<li>7 ANNI DI GARANZIA sul corpo caldaia.<\/li>\n<li>TOTAL CLEAN braciere autopulente; pulizia automatica del fascio tubiero.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Massima concezione del compatto, garantisce la maggiore efficienza dello scambiatore con i suoi 4 giri di fumo. Vivere Compact Power Plus significa applicare l&#8217;estremo design domestico alla vita industriale della formula Hybrid Bi- Power. La particolarita\u0300 di Compact Power Plus e\u0300 rappresentata da un&#8217;unica camera di combustione capace di accogliere, nella sua \u201cbocca di fuoco\u201d, indistintamente pellet e altri combustibili triti.<\/p>\n","protected":false},"featured_media":54280,"template":"","meta":{"_acf_changed":false},"product_brand":[4048],"product_cat":[4523],"product_tag":[1974],"class_list":{"0":"post-54279","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-pasqualicchio","7":"product_cat-caldaie-policombustibili","8":"product_tag-caldaie-policombustibili-pasqualicchio","9":"product_shipping_class-caldaie-policombustibili","10":"pa_potenza-100-kw","11":"pa_potenza-25-kw","12":"pa_potenza-32-kw","13":"pa_potenza-38-kw","14":"pa_potenza-48-kw","15":"pa_potenza-60-kw","16":"pa_potenza-80-kw","17":"sales-flash-overlay","18":"woocommerce-text-align-center","19":"woocommerce-image-align-center","20":"do-quantity-buttons","22":"first","23":"instock","24":"taxable","25":"shipping-taxable","26":"purchasable","27":"product-type-variable"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.fokussrl.com\/it\/wp-json\/wp\/v2\/product\/54279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fokussrl.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.fokussrl.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fokussrl.com\/it\/wp-json\/wp\/v2\/media\/54280"}],"wp:attachment":[{"href":"https:\/\/www.fokussrl.com\/it\/wp-json\/wp\/v2\/media?parent=54279"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.fokussrl.com\/it\/wp-json\/wp\/v2\/product_brand?post=54279"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.fokussrl.com\/it\/wp-json\/wp\/v2\/product_cat?post=54279"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.fokussrl.com\/it\/wp-json\/wp\/v2\/product_tag?post=54279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}